{"id":7464,"date":"2026-05-13T16:00:20","date_gmt":"2026-05-13T14:00:20","guid":{"rendered":"https:\/\/am-israel-farafina.com\/?p=7464"},"modified":"2026-05-13T16:00:22","modified_gmt":"2026-05-13T14:00:22","slug":"les-communautes-africaines-negocient-leurs-identites-juives","status":"publish","type":"post","link":"https:\/\/am-israel-farafina.com\/index.php\/2026\/05\/13\/les-communautes-africaines-negocient-leurs-identites-juives\/","title":{"rendered":"Les communaut\u00e9s africaines n\u00e9gocient leurs identit\u00e9s juives"},"content":{"rendered":"<p>La 6e Conf\u00e9rence internationale de la Soci\u00e9t\u00e9 internationale pour l&rsquo;\u00e9tude du juda\u00efsme africain (ISSAJ) s&rsquo;est tenue les 9 et 10 mars 2026 au Mus\u00e9e d&rsquo;art et d&rsquo;histoire du juda\u00efsme (mahJ) \u00e0 Paris. R\u00e9unissant des chercheurs de diverses disciplines et r\u00e9gions, la conf\u00e9rence a explor\u00e9 le th\u00e8me \u00ab Au-del\u00e0 des fleuves de Koush : les communaut\u00e9s africaines et la construction de leurs identit\u00e9s juives \u00bb.<\/p><p>En raison de l&rsquo;escalade du conflit au Moyen-Orient, l&rsquo;\u00e9v\u00e9nement s&rsquo;est d\u00e9roul\u00e9 en format hybride, permettant ainsi aux chercheurs ne pouvant se d\u00e9placer de participer \u00e0 distance.<\/p><p>Pendant ces deux jours, la conf\u00e9rence a offert une exploration riche et nuanc\u00e9e de la diversit\u00e9 de la vie juive sur le continent africain et dans sa diaspora. Les communications ont abord\u00e9 un large \u00e9ventail de sujets, des perspectives historiques et bibliques aux analyses ethnographiques et politiques contemporaines, mettant en lumi\u00e8re aussi bien les traditions ancestrales que les formes \u00e9mergentes d&rsquo;identification juive en Afrique subsaharienne, en Isra\u00ebl, en Am\u00e9rique latine et dans d&rsquo;autres r\u00e9gions.<\/p><p>L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 enrichi par la pr\u00e9sence de plusieurs personnes issues de diverses communaut\u00e9s juives africaines et noires, qui ont apport\u00e9 de pr\u00e9cieuses contributions. Des pr\u00e9sentations pertinentes ont \u00e9galement \u00e9t\u00e9 donn\u00e9es par des repr\u00e9sentants d&rsquo;organisations juives de premier plan, notamment le Conseil juif du Commonwealth. Kulanu, une organisation partenaire de l&rsquo;ISSAJ, a \u00e9galement pr\u00e9sent\u00e9 un expos\u00e9 sur des sujets li\u00e9s \u00e0 la recherche et \u00e0 ses activit\u00e9s.<\/p><p>Au-del\u00e0 des pr\u00e9sentations, la conf\u00e9rence a favoris\u00e9 le dialogue entre chercheurs \u00e9mergents et confirm\u00e9s, membres de la communaut\u00e9 et participants repr\u00e9sentant diverses perspectives. Un avantage notable a \u00e9t\u00e9 la mise \u00e0 disposition d&rsquo;une plateforme permettant l&rsquo;expression de points de vue divergents dans une atmosph\u00e8re \u00e0 la fois ouverte et respectueuse, soulignant ainsi le r\u00f4le de l&rsquo;ISSAJ en tant que forum privil\u00e9gi\u00e9 pour ce type d&rsquo;\u00e9changes constructifs.<\/p><p>Pour l&rsquo;avenir, l&rsquo;ISSAJ pr\u00e9voit de capitaliser sur le succ\u00e8s de sa sixi\u00e8me rencontre en organisant des webinaires r\u00e9guliers au moins une fois par an. Ces r\u00e9unions en ligne offriront de nouvelles opportunit\u00e9s d&rsquo;\u00e9changes universitaires, permettant aux participants de diff\u00e9rentes r\u00e9gions de poursuivre les discussions, de partager leurs nouvelles recherches et de renforcer le r\u00e9seau international croissant de chercheurs et de communaut\u00e9s int\u00e9ress\u00e9s par le juda\u00efsme africain. D&rsquo;autres informations suivront.<\/p><p>Message d&rsquo;Edith Bruder, pr\u00e9sidente de l&rsquo;ISSAJ&nbsp;:<\/p><p>\u00c0 l&rsquo;issue de cette sixi\u00e8me r\u00e9union, plusieurs changements ont \u00e9t\u00e9 mis en \u0153uvre afin de renforcer la pertinence de l&rsquo;ISSAJ pour ses membres actuels et les autres acteurs partageant notre vision. D\u00e9sormais, l&rsquo;ISSAJ passera d&rsquo;une organisation \u00e0 un r\u00e9seau dot\u00e9 d&rsquo;une liste de diffusion. Cette conf\u00e9rence inspirante nous a \u00e9galement incit\u00e9s \u00e0 lancer une lettre d&rsquo;information pour maintenir le lien entre nos membres. Par ailleurs, cet \u00e9v\u00e9nement r\u00e9gulier ouvre la voie \u00e0 de nouvelles initiatives, telles que l&rsquo;organisation de webinaires et de sessions plus approfondies de mani\u00e8re r\u00e9guli\u00e8re.<\/p><p>Vos suggestions sont les bienvenues.<\/p><p>Enfin, nous sommes ravis d&rsquo;annoncer l&rsquo;arriv\u00e9e de deux nouveaux membres au sein du conseil d&rsquo;administration de l&rsquo;ISSAJ&nbsp;: Ayode Daniel Dossou de l&rsquo;Institut de hautes \u00e9tudes internationales et du d\u00e9veloppement de Gen\u00e8ve et Noam Cohen de l&rsquo;Universit\u00e9 de Leipzig.<\/p>","protected":false},"excerpt":{"rendered":"<p>La 6e Conf\u00e9rence internationale de la Soci\u00e9t\u00e9<\/p>\n","protected":false},"author":1,"featured_media":7462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"footnotes":""},"categories":[220,219,218],"tags":[],"class_list":["post-7464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-actualite-juive-afrique","category-actualite-juive"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/posts\/7464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/comments?post=7464"}],"version-history":[{"count":1,"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/posts\/7464\/revisions"}],"predecessor-version":[{"id":7465,"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/posts\/7464\/revisions\/7465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/media\/7462"}],"wp:attachment":[{"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/media?parent=7464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/categories?post=7464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/am-israel-farafina.com\/index.php\/wp-json\/wp\/v2\/tags?post=7464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}